{"id":23217,"date":"2025-12-20T11:18:42","date_gmt":"2025-12-20T10:18:42","guid":{"rendered":"https:\/\/reteitalianaism.it\/reteism\/?p=23217"},"modified":"2025-12-20T11:19:21","modified_gmt":"2025-12-20T10:19:21","slug":"il-movimento-bds-chiede-la-mobilitazione-della-societa-civile-mentre-il-partner-elsc-avvia-azioni-legali-per-fermare-una-nave-battente-bandiera-portoghese-che-trasporta-440-tonnellate-di-armi-destinat","status":"publish","type":"post","link":"https:\/\/reteitalianaism.it\/reteism\/index.php\/2025\/12\/20\/il-movimento-bds-chiede-la-mobilitazione-della-societa-civile-mentre-il-partner-elsc-avvia-azioni-legali-per-fermare-una-nave-battente-bandiera-portoghese-che-trasporta-440-tonnellate-di-armi-destinat\/","title":{"rendered":"Il movimento BDS chiede la mobilitazione della societ\u00e0 civile mentre il partner ELSC avvia azioni legali per fermare una nave battente bandiera portoghese che trasporta 440 tonnellate di armi destinate allo stato genocida Israele."},"content":{"rendered":"<hr \/>\n<p>20 dicembre 2025<\/p>\n<p><a href=\"https:\/\/bdsmovement.net\/BDS-Call-Mobilization-ELSC-File-Legal-Actions\">BDS movement calls for civil society mobilization as partner ELSC initiates legal actions to stop Portuguese-flagged vessel carrying 440 tonnes of arms to genocidal Israel. | BDS Movement<\/a><\/p>\n<div id=\"attachment_23218\" style=\"width: 445px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/reteitalianaism.it\/reteism\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-20-110609.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-23218\" class=\" wp-image-23218\" src=\"http:\/\/reteitalianaism.it\/reteism\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-20-110609-300x118.png\" alt=\"\" width=\"435\" height=\"171\" srcset=\"https:\/\/reteitalianaism.it\/reteism\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-20-110609-300x118.png 300w, https:\/\/reteitalianaism.it\/reteism\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-20-110609-1024x404.png 1024w, https:\/\/reteitalianaism.it\/reteism\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-20-110609-768x303.png 768w, https:\/\/reteitalianaism.it\/reteism\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-20-110609.png 1268w\" sizes=\"auto, (max-width: 435px) 100vw, 435px\" \/><\/a><p id=\"caption-attachment-23218\" class=\"wp-caption-text\">dal sito bdsmovement.net<\/p><\/div>\n<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">L&#8217;European Legal Support Center (ELSC), con il supporto degli avvocati portoghesi Carmo Afonso e Madalena Vaz da Silva, ha presentato una denuncia penale alle autorit\u00e0 giudiziarie portoghesi contro il proprietario tedesco registrato, Gerdes Bereederungs GmbH &amp; Co. KG, della nave battente bandiera portoghese Holger G (IMO 9995894).<\/span><\/span><\/p>\n<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Chiedono l&#8217;avvio di un procedimento penale, un&#8217;indagine formale e il sequestro immediato del carico militare a bordo dell&#8217;Holger G. <\/span><\/span><\/p>\n<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">L&#8217;Holger G \u00e8 partito da Chennai, in India, il 1\u00b0 novembre ed \u00e8 diretto in Israele con arrivo previsto per il 31 dicembre 2025. La documentazione scoperta dal sito investigativo The Ditch ha rivelato che il carico a bordo dell&#8217;Holger G. La spedizione sarebbe destinata alla pi\u00f9 grande azienda militare israeliana, Elbit Systems, e alla sua sussidiaria produttrice di munizioni, IMI Systems.<\/span><\/span><!--more--><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Parallelamente, l&#8217;ELSC ha informato la compagnia assicurativa per la responsabilit\u00e0 civile verso terzi della nave, NorthStandard Limited, dei rischi legali e normativi connessi alla fornitura di tale copertura, alla luce dell&#8217;Avviso agli esportatori del Regno Unito 2024\/20, che sospende le licenze per l&#8217;esportazione di determinati beni militari in Israele e considera reato per i cittadini del Regno Unito agevolare tale fornitura.<\/span><\/span><\/p>\n<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">L&#8217;ELSC chiede a NorthStandard di sospendere la copertura assicurativa per la Holger G e per qualsiasi altra nave che trasporti beni militari o a duplice uso la cui esportazione in Israele sia vietata dalla legge britannica e di implementare procedure di due diligence rafforzate per il futuro.<\/span><\/span><\/p>\n<p><strong><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Mahmoud Nawajaa, Coordinatore Generale del movimento BDS, ha dichiarato:<\/span><\/span><\/strong><\/p>\n<p class=\"lRu31\" dir=\"ltr\"><em><span class=\"HwtZe\" lang=\"it\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">&#8220;Il movimento BDS guidato dai palestinesi accoglie con favore questa azione legale, che sostiene gli sforzi degli attivisti provenienti dal Mozambico, dove l&#8217;Holger G \u00e8 stato revisionato l&#8217;ultima volta, e diretti in Portogallo, che si stanno mobilitando e chiedono il sequestro immediato del carico illegale. A bordo dell&#8217;Holger G ci sono proiettili, bombe da mortaio e acciaio di qualit\u00e0 militare. Sia chiaro: si tratta di un carico di materiale militare che Israele user\u00e0 per uccidere i palestinesi. Il &#8220;cessate il fuoco&#8221; non ha posto fine alle uccisioni di palestinesi da parte di Israele e all&#8217;aggressione contro gli stati vicini. Il genocidio a Gaza \u00e8 in corso. Solo l&#8217;assunzione di responsabilit\u00e0 e sanzioni mirate fermeranno i crimini di Israele&#8221;.<\/span><\/span> <\/span><\/em><\/p>\n<p class=\"lRu31\" dir=\"ltr\"><em><span class=\"HwtZe\" lang=\"it\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">&#8220;Rendiamo omaggio all&#8217;ELSC per aver intrapreso queste storiche azioni legali per fermare il trasporto illegale di materiale militare verso Israele, stato genocida. Abbiamo bisogno di ulteriore sostegno ora per fermare urgentemente l&#8217;Holger G. Chiediamo ai sostenitori in Portogallo, nel Mediterraneo, cos\u00ec come nel Regno Unito e in Germania, di mobilitarsi ora.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Dobbiamo continuare a fare pressione su questi governi affinch\u00e9 fermino la nave e impongano sanzioni legali e mirate a Israele, tra cui un embargo militare totale&#8221;.<\/span><\/span><\/span><\/em><\/p>\n<p class=\"lRu31\" dir=\"ltr\"><strong><span class=\"HwtZe\" lang=\"it\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Giovanni Fassina, Direttore Esecutivo dell&#8217;ELSC, ha dichiarato: <\/span><\/span><\/span><\/strong><\/p>\n<p class=\"lRu31\" dir=\"ltr\"><em><span class=\"HwtZe\" lang=\"it\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">&#8220;Questo caso \u00e8 cruciale perch\u00e9 tocca il cuore degli obblighi degli Stati di impedire il trasferimento di armi che contribuiscono al genocidio. Le autorit\u00e0 portoghesi hanno il dovere chiaro e immediato, ai sensi del diritto nazionale, europeo e internazionale, di interrompere il trasporto di carichi militari sotto la loro bandiera e di sequestrare la nave. Sebbene questa azione legale sia necessaria, non \u00e8 di per s\u00e9 sufficiente: il suo impatto dipende dal potere collettivo della societ\u00e0 civile e dai movimenti che la<\/span><\/span><\/span><\/em><span class=\"HwtZe\" lang=\"it\"><em><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\"> sostengono per mobilitare la pressione e garantire che la legge venga applicata nella pratica, non solo sulla carta.&#8221;<\/span><\/span><\/em> <\/span><\/p>\n<p class=\"lRu31\" dir=\"ltr\"><span class=\"HwtZe\" lang=\"it\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Per ulteriori informazioni sugli obblighi giuridici degli Stati di bandiera, di approdo e costieri secondo il Diritto del Mare, si veda il <a href=\"https:\/\/bdsmovement.net\/sites\/default\/files\/2025-03\/ASCOMARE%20Legal%20Opinion%20_%20Innocent%20Passage%20and%20Due%20Diligence.pdf\">parere legale dell&#8217;ASCOMARE<\/a>.<\/span><\/span> <\/span><\/p>\n<p class=\"lRu31\" dir=\"ltr\"><span class=\"HwtZe\" lang=\"it\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Per ulteriori informazioni sugli obblighi giuridici delle imprese di fronte al genocidio israeliano, si veda lo studio della Dott.ssa Irene Pietropaoli <a href=\"https:\/\/www.somo.nl\/wp-content\/uploads\/2024\/06\/Obligations-of-Third-States-and-Corporations-to-Prevent-and-Punish-Genocide-in-Gaza-3.pdf\">&#8220;Obblighi di Stati terzi e imprese di prevenire e punire il genocidio a Gaza&#8221;<\/a>.<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>20 dicembre 2025 BDS movement calls for civil society mobilization as partner ELSC initiates legal actions to stop Portuguese-flagged vessel carrying 440 tonnes of arms to genocidal Israel. | BDS Movement L&#8217;European Legal Support Center (ELSC), con il supporto degli &hellip; <a href=\"https:\/\/reteitalianaism.it\/reteism\/index.php\/2025\/12\/20\/il-movimento-bds-chiede-la-mobilitazione-della-societa-civile-mentre-il-partner-elsc-avvia-azioni-legali-per-fermare-una-nave-battente-bandiera-portoghese-che-trasporta-440-tonnellate-di-armi-destinat\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[76,253,25,179],"class_list":["post-23217","post","type-post","status-publish","format-standard","hentry","category-info","tag-bds","tag-boicottaggio","tag-gaza","tag-genocidio"],"_links":{"self":[{"href":"https:\/\/reteitalianaism.it\/reteism\/index.php\/wp-json\/wp\/v2\/posts\/23217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reteitalianaism.it\/reteism\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reteitalianaism.it\/reteism\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reteitalianaism.it\/reteism\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/reteitalianaism.it\/reteism\/index.php\/wp-json\/wp\/v2\/comments?post=23217"}],"version-history":[{"count":2,"href":"https:\/\/reteitalianaism.it\/reteism\/index.php\/wp-json\/wp\/v2\/posts\/23217\/revisions"}],"predecessor-version":[{"id":23220,"href":"https:\/\/reteitalianaism.it\/reteism\/index.php\/wp-json\/wp\/v2\/posts\/23217\/revisions\/23220"}],"wp:attachment":[{"href":"https:\/\/reteitalianaism.it\/reteism\/index.php\/wp-json\/wp\/v2\/media?parent=23217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reteitalianaism.it\/reteism\/index.php\/wp-json\/wp\/v2\/categories?post=23217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reteitalianaism.it\/reteism\/index.php\/wp-json\/wp\/v2\/tags?post=23217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}